{"id":46726,"date":"2024-08-13T11:00:00","date_gmt":"2024-08-13T14:00:00","guid":{"rendered":"https:\/\/reportei.com\/?p=46726"},"modified":"2024-08-13T16:43:56","modified_gmt":"2024-08-13T19:43:56","slug":"overview-de-reportei-analysez-les-metriques-les-plus-importantes","status":"publish","type":"post","link":"https:\/\/reportei.com\/fr\/overview-de-reportei-analysez-les-metriques-les-plus-importantes\/","title":{"rendered":"Overview de Reportei :\u00a0analysez les m\u00e9triques les plus importantes de chaque projet sur un seul \u00e9cran"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"h-d-couvrez-le-reportei-overview-et-apprenez-comment-obtenir-une-vue-d-ensemble-des-performances-de-vos-projets-sur-un-m-me-tableau-de-bord\"><strong>D\u00e9couvrez le Reportei Overview et apprenez comment obtenir une vue d&rsquo;ensemble des performances de vos projets sur un m\u00eame tableau de bord.<\/strong><\/h2>\n\n\n\n<p>Le Overview est arriv\u00e9 sur Reportei pour aider les agences, les gestionnaires de trafic et d&rsquo;autres professionnels du marketing \u00e0 optimiser la gestion de multiples projets et la prise de d\u00e9cision au quotidien.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 des fonctionnalit\u00e9s permettant un suivi rapide des donn\u00e9es et des objectifs, cette nouveaut\u00e9 offre une vue consolid\u00e9e et efficace de tous les indicateurs importants des comptes int\u00e9gr\u00e9s \u00e0 notre plateforme.<\/p>\n\n\n\n<p>C&rsquo;est pourquoi nous avons pr\u00e9par\u00e9 cet article pour explorer les d\u00e9tails de cet outil. D\u00e9couvrez comment ses fonctionnalit\u00e9s peuvent transformer votre mani\u00e8re de g\u00e9rer et d&rsquo;\u00e9valuer vos strat\u00e9gies marketing. Suivez-nous !<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-qu-est-ce-que-le-reportei-overview\"><strong>Qu&rsquo;est-ce que le Reportei Overview ?<\/strong><\/h3>\n\n\n\n<p>Bien que Reportei dispose d\u00e9j\u00e0 de fonctionnalit\u00e9s avanc\u00e9es pour la collecte de donn\u00e9es et le suivi des objectifs \u2013 comme les dashboards et <a href=\"https:\/\/reportei.com\/fr\/reportei-control\/\">le Contr\u00f4le des Indicateurs<\/a> \u2013, de nombreux clients exprimaient le besoin d&rsquo;avoir une vue d&rsquo;ensemble des performances de toutes leurs comptes en un seul endroit, sans avoir \u00e0 acc\u00e9der \u00e0 chaque projet individuellement.<\/p>\n\n\n\n<p>Ainsi, le Overview a \u00e9t\u00e9 cr\u00e9\u00e9 pour r\u00e9pondre \u00e0 ce besoin. En r\u00e9sum\u00e9, cette fonctionnalit\u00e9 offre une vue consolid\u00e9e des indicateurs et des objectifs de diff\u00e9rents projets sur une m\u00eame interface.<\/p>\n\n\n\n<p>Cette centralisation des informations permet non seulement de gagner un temps pr\u00e9cieux pour les analystes et les gestionnaires, mais aussi de prendre des d\u00e9cisions plus rapides et plus pr\u00e9cises. En effet, avec une vue claire et imm\u00e9diate des indicateurs, il devient facile d&rsquo;identifier rapidement quels projets n\u00e9cessitent plus d&rsquo;attention et quelles strat\u00e9gies g\u00e9n\u00e8rent un retour sur investissement.<\/p>\n\n\n\n<p>En d&rsquo;autres termes, c&rsquo;est un outil id\u00e9al pour les agences de marketing, les gestionnaires de trafic travaillant sur plusieurs comptes et les franchises. Le Overview facilite le suivi continu et pr\u00e9cis des campagnes num\u00e9riques, en gardant le focus sur les d\u00e9cisions strat\u00e9giques et la croissance de vos projets.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"583\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-1024x583.png\" alt=\"\" class=\"wp-image-46727\" style=\"width:1196px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-1024x583.png 1024w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-300x171.png 300w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-768x437.png 768w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-1536x874.png 1536w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-750x427.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr-400x228.png 400w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-table-fr.png 1868w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-d-couvrez-comment-g-rer-les-m-triques-des-projets-avec-le-reportei-overview\"><strong>D\u00e9couvrez comment g\u00e9rer les m\u00e9triques des projets avec le Reportei Overview<\/strong><\/h3>\n\n\n\n<p>Le Reportei Overview est d\u00e9sormais disponible pour \u00eatre utilis\u00e9 et test\u00e9 dans le menu sup\u00e9rieur de notre application.<\/p>\n\n\n\n<p>Ainsi, \u00e0 c\u00f4t\u00e9 de \u00ab\u00a0Mes projets\u00a0\u00bb, vous trouverez un bouton d\u00e9di\u00e9 \u00e0 cette nouvelle fonctionnalit\u00e9. Ici, vous pourrez configurer votre \u00e9cran de mani\u00e8re totalement personnalis\u00e9e.<\/p>\n\n\n\n<p>En effet, vous avez toute la libert\u00e9 de d\u00e9velopper votre tableau de bord en fonction des objectifs des projets. Vous pouvez utiliser des templates pr\u00e9d\u00e9finis comme r\u00e9f\u00e9rence, ajouter des objectifs pour faciliter le suivi, et bien plus encore.<\/p>\n\n\n\n<p>Nous vous d\u00e9voilons ci-apr\u00e8s tous les d\u00e9tails sur les possibilit\u00e9s offertes par cet outil. On y va ?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-personnalisez-les-onglets-en-fonction-des-objectifs\"><strong>Personnalisez les onglets en fonction des objectifs<\/strong><\/h3>\n\n\n\n<p>Dans le Reportei Overview, la personnalisation des pages est une fonctionnalit\u00e9 essentielle pour organiser et optimiser la visualisation de vos projets. En cr\u00e9ant plusieurs onglets \u2013 \u00e0 partir de templates pr\u00e9d\u00e9finis ou d&rsquo;une page blanche \u2013, vous pouvez structurer votre tableau de bord en fonction de diff\u00e9rents objectifs. Cela facilite le suivi et l&rsquo;analyse des indicateurs les plus pertinents.<\/p>\n\n\n\n<p><p style=\"white-space: normal; caret-color: rgb(0, 0, 0); color: rgb(0, 0, 0);\">Par exemple, vous pouvez diviser les donn\u00e9es selon diff\u00e9rents services, tels que le SEO, le trafic payant, ou m\u00eame par niche ou r\u00e9gion, dans le cas de franchises.Cette flexibilit\u00e9 permet \u00e0 chaque onglet d&rsquo;\u00eatre d\u00e9di\u00e9 \u00e0 un ensemble sp\u00e9cifique de projets, offrant ainsi une vue claire et organis\u00e9e des performances de chaque domaine.<\/p><\/p>\n\n\n\n<p><p style=\"white-space: normal; caret-color: rgb(0, 0, 0); color: rgb(0, 0, 0);\">Gr\u00e2ce \u00e0 cela, le Overview offre une vision holistique des principaux indicateurs, facilitant l&rsquo;identification rapide des comportements vari\u00e9s entre les comptes et aidant \u00e0 une prise de d\u00e9cision plus rapide dans la gestion quotidienne des projets.<\/p><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"569\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-1024x569.png\" alt=\"\" class=\"wp-image-46732\" style=\"width:1196px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-1024x569.png 1024w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-300x167.png 300w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-768x427.png 768w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-750x417.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr-400x222.png 400w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-pages-fr.png 1037w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-ajoutez-les-m-triques-les-plus-pertinentes\">Ajoutez les m\u00e9triques les plus pertinentes<\/h3>\n\n\n\n<p>De plus, dans le cadre de la personnalisation, le Reportei Overview vous permet \u00e9galement de d\u00e9finir quelles m\u00e9triques doivent appara\u00eetre et dans quel ordre, garantissant ainsi que les informations les plus importantes soient toujours en \u00e9vidence et facilement accessibles.<\/p>\n\n\n\n<p>Vous pouvez ainsi ajouter des m\u00e9triques provenant de l&rsquo;une des int\u00e9grations disponibles sur notre plateforme ou cr\u00e9er des m\u00e9triques calcul\u00e9es pour obtenir une vision encore plus compl\u00e8te des r\u00e9sultats.<\/p>\n\n\n\n<p>Par exemple, vous pouvez additionner les montants investis dans tous les canaux de m\u00e9dias payants pour suivre l&rsquo;investissement total r\u00e9alis\u00e9 dans chaque projet. Ce dispositif est particuli\u00e8rement utile pour la gestion des franchises, o\u00f9 il est n\u00e9cessaire de surveiller les performances dans diff\u00e9rentes r\u00e9gions afin de d\u00e9terminer lesquelles offrent le meilleur retour sur investissement (ROI).<\/p>\n\n\n\n<p>En outre, \u00e0 la fin du tableau, vous pouvez voir la somme d&rsquo;un indicateur sp\u00e9cifique et d\u00e9couvrir, par exemple, combien l&rsquo;agence ou le franchiseur investit dans l&rsquo;ensemble de ses projets.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" width=\"813\" height=\"815\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr.png\" alt=\"\" class=\"wp-image-46737\" style=\"width:1196px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr.png 813w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr-300x300.png 300w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr-150x150.png 150w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr-768x770.png 768w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr-750x752.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-metrics-fr-400x401.png 400w\" sizes=\"(max-width: 813px) 100vw, 813px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-d-finissez-la-p-riode-d-analyse\">D\u00e9finissez la p\u00e9riode d&rsquo;analyse<\/h3>\n\n\n\n<p>Apr\u00e8s avoir d\u00e9fini vos m\u00e9triques, vous aurez la flexibilit\u00e9 de choisir comment vous souhaitez visualiser vos donn\u00e9es, que ce soit en temps r\u00e9el ou de mani\u00e8re r\u00e9trospective. Cela permet une analyse pr\u00e9cise et personnalis\u00e9e en fonction de vos besoins sp\u00e9cifiques.<\/p>\n\n\n\n<p>En optant pour le suivi des m\u00e9triques en temps r\u00e9el, vous b\u00e9n\u00e9ficierez d&rsquo;une vue mise \u00e0 jour et imm\u00e9diate des performances de vos projets. C&rsquo;est id\u00e9al pour surveiller les campagnes en cours et prendre des d\u00e9cisions rapides bas\u00e9es sur les informations les plus r\u00e9centes.<\/p>\n\n\n\n<p>D&rsquo;autre part, la s\u00e9lection de p\u00e9riodes d&rsquo;analyse r\u00e9trospectives vous permet de r\u00e9aliser une analyse d\u00e9taill\u00e9e des performances pass\u00e9es. Cela est particuli\u00e8rement utile pour \u00e9valuer les tendances, comparer les r\u00e9sultats de diff\u00e9rentes p\u00e9riodes et comprendre l&rsquo;impact des strat\u00e9gies mises en place pr\u00e9c\u00e9demment.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"723\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-1024x723.png\" alt=\"\" class=\"wp-image-46742\" style=\"width:1196px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-1024x723.png 1024w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-300x212.png 300w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-768x542.png 768w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-750x529.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr-400x282.png 400w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-period-fr.png 1036w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-cr-ez-des-objectifs-pour-les-projets\">Cr\u00e9ez des objectifs pour les projets<\/h3>\n\n\n\n<p>En plus de suivre les indicateurs, le Reportei Overview permet de d\u00e9finir des objectifs et des limites pour vos m\u00e9triques, ce qui facilite le suivi et l&rsquo;\u00e9valuation de la progression vers vos objectifs.<\/p>\n\n\n\n<p>En cliquant sur une m\u00e9trique sp\u00e9cifique, vous pouvez ajouter une valeur de r\u00e9f\u00e9rence, comme une limite d&rsquo;investissement \u00e0 respecter en m\u00e9dias payants ou un nombre total de conversions \u00e0 atteindre \u00e0 la fin d&rsquo;une p\u00e9riode. Cela rend la visualisation des r\u00e9sultats encore plus pr\u00e9cise.<\/p>\n\n\n\n<p>Ainsi, vous pouvez rapidement identifier les domaines qui n\u00e9cessitent des ajustements et prendre des d\u00e9cisions \u00e9clair\u00e9es pour optimiser les r\u00e9sultats.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"975\" height=\"674\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr.png\" alt=\"\" class=\"wp-image-46747\" style=\"width:1196px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr.png 975w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr-300x207.png 300w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr-768x531.png 768w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr-750x518.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-comparison-value-fr-400x277.png 400w\" sizes=\"(max-width: 975px) 100vw, 975px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-suivez-la-performance-de-l-quipe\">Suivez la performance de l&rsquo;\u00e9quipe<\/h3>\n\n\n\n<p>Enfin, le Overview vous permet de suivre de pr\u00e8s la performance de chaque membre de l&rsquo;\u00e9quipe enregistr\u00e9 sur la plateforme. Vous pouvez filtrer les indicateurs des projets en fonction de chaque professionnel de l&rsquo;entreprise, ce qui facilite le suivi des performances individuelles et collectives.<\/p>\n\n\n\n<p>Cela permet aux gestionnaires de prendre des d\u00e9cisions plus \u00e9clair\u00e9es et cibl\u00e9es, en s&rsquo;assurant que tous les collaborateurs sont align\u00e9s sur les objectifs et les buts fix\u00e9s pour les projets.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"759\" height=\"821\" src=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-teammember-fr.png\" alt=\"\" class=\"wp-image-46752\" style=\"width:759px;height:auto\" srcset=\"https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-teammember-fr.png 759w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-teammember-fr-277x300.png 277w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-teammember-fr-750x811.png 750w, https:\/\/reportei.com\/wp-content\/uploads\/2024\/08\/overview-teammember-fr-400x433.png 400w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-comment-souscrire-au-reportei-overview\">Comment souscrire au Reportei Overview ?<\/h3>\n\n\n\n<p>Le Overview est une fonctionnalit\u00e9 <a href=\"https:\/\/reportei.com\/fr\/abonnements-et-tarifs\/\">du plan Premium<\/a> de Reportei et est d\u00e9j\u00e0 disponible pour ces clients, en plus de nombreuses autres fonctionnalit\u00e9s exclusives. Par exemple, le Contr\u00f4le des Indicateurs, l&rsquo;utilisation d&rsquo;automatisations de rapports illimit\u00e9es, une plus grande capacit\u00e9 d&rsquo;inscription d&rsquo;utilisateurs, et bien plus encore.<\/p>\n\n\n\n<p>Cependant, les clients des plans Starter et Pro peuvent \u00e9galement tester l&rsquo;outil gratuitement pendant 7 jours et d\u00e9couvrir en pratique comment il aide au suivi des indicateurs des projets.<\/p>\n\n\n\n<p>Autrement dit, vous <a href=\"https:\/\/app.reportei.com\/login\">pouvez d\u00e8s maintenant acc\u00e9der \u00e0 votre compte<\/a> et commencer \u00e0 profiter des avantages du Overview pour un suivi plus pr\u00e9cis des r\u00e9sultats au quotidien !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le Reportei Overview et apprenez comment obtenir une vue d&rsquo;ensemble des performances de vos projets sur un m\u00eame tableau de bord.<\/p>\n","protected":false},"author":18,"featured_media":46757,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4044,3547],"tags":[],"class_list":["post-46726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lanalyse-des-resultats","category-reportei-3"],"_links":{"self":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts\/46726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/comments?post=46726"}],"version-history":[{"count":1,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts\/46726\/revisions"}],"predecessor-version":[{"id":46762,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts\/46726\/revisions\/46762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/media\/46757"}],"wp:attachment":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/media?parent=46726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/categories?post=46726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/tags?post=46726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}