{"id":26845,"date":"2022-10-27T11:00:02","date_gmt":"2022-10-27T14:00:02","guid":{"rendered":"https:\/\/servidor.reportei.com\/?p=26845"},"modified":"2022-11-14T09:47:20","modified_gmt":"2022-11-14T12:47:20","slug":"facebook-business-guide-complet-de-la-plateforme","status":"publish","type":"post","link":"https:\/\/reportei.com\/fr\/facebook-business-guide-complet-de-la-plateforme\/","title":{"rendered":"Facebook Business : guide complet de la plateforme"},"content":{"rendered":"<h2><strong>D\u00e9couvrez ce que c\u2019est, ses avantages, et comment utiliser Facebook Business dans votre strat\u00e9gie de marketing digital<\/strong><\/h2>\n<p><b>Facebook Business<\/b><span style=\"font-weight: 400;\">, aussi connu sous le nom de <\/span><b>Meta Business<\/b><span style=\"font-weight: 400;\">, est un outil cr\u00e9\u00e9 pour aider les entreprises \u00e0 augmenter la port\u00e9e sur la plateforme et l\u2019engagement avec leurs diff\u00e9rents publics.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Son objectif est de rassembler en un seul endroit tous les actifs de votre marque pour d\u00e9velopper des strat\u00e9gies de marketing digital sur les r\u00e9seaux, que ce soit au moyen de pages, de comptes publicitaires, ou d\u2019autres fonctionnalit\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Puisqu\u2019il s\u2019agit d\u2019une plateforme tr\u00e8s globale et compl\u00e8te, nous avons pr\u00e9par\u00e9 cet article pour vous dire <\/span><b>tout ce qu\u2019il faut savoir sur Facebook Business<\/b><span style=\"font-weight: 400;\">, les ressources dont vous pouvez profiter, et comment cr\u00e9er et g\u00e9rer votre compte. C\u2019est parti !<\/span><\/p>\n<h2><strong>Qu\u2019est-ce que Facebook Business ?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Comme \u00e9voqu\u00e9 pr\u00e9c\u00e9demment, Facebook Business est un outil dont l\u2019objectif est d\u2019aider des entreprises \u00e0 <\/span><b>g\u00e9rer leurs actifs sur Facebook et Instagram<\/b><span style=\"font-weight: 400;\"> \u00e0 un seul endroit.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, les \u00e9quipes et analystes de marketing peuvent <\/span><b>obtenir de meilleurs r\u00e9sultats \u00e0 partir des actions d\u00e9velopp\u00e9es<\/b><span style=\"font-weight: 400;\">, gagnant ainsi en temps et en efficacit\u00e9 sur leur routine de travail.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Par exemple, il est possible de voir et de r\u00e9pondre aux messages laiss\u00e9s sur votre page ou profil, de programmer des publications, de cr\u00e9er des campagnes de publicit\u00e9 et, bien entendu, de suivre les <\/span><span style=\"font-weight: 400;\">rapports de Facebook Ads<\/span><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour r\u00e9aliser tout cela, Facebook Business comporte divers outils int\u00e9gr\u00e9s \u00e0 la plateforme, comme vous pouvez le lire dans la suite de l\u2019article.<\/span><\/p>\n<h3><strong>Outils disponibles sur la plateforme<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Apr\u00e8s avoir cr\u00e9\u00e9 un compte de Business Manager, vous commencerez \u00e0 avoir acc\u00e8s aux actifs de la plateforme. Parmi ces fonctionnalit\u00e9s, on retrouve :<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>la gestion de la page ou du profil de votre entreprise, <\/b><span style=\"font-weight: 400;\">avec des ressources vari\u00e9es pour programmer les publications, r\u00e9pondre aux messages et acc\u00e9der aux insights \u2013 cela fait d\u2019ailleurs partie de l\u2019outil Facebook Business Suite, qui aide \u00e0 la gestion des activit\u00e9s sur les canaux ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>les comptes publiitaires <\/b><span style=\"font-weight: 400;\">pour publier et suivre les strat\u00e9gies de publicit\u00e9 sur les r\u00e9seaux sociaux associ\u00e9s \u00e0 Meta Business ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>l\u2019int\u00e9gration avec des applications <\/b><span style=\"font-weight: 400;\">utilis\u00e9es en compl\u00e9ment aux actions d\u00e9velopp\u00e9es sur les canaux ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>l\u2019installation et la gestion de Pixel<\/b><span style=\"font-weight: 400;\">, qui permettent de suivre les conversions faites sur le site et la cr\u00e9ation de publics pour les campagnes de remarketing ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>la segmentation des publics<\/b><span style=\"font-weight: 400;\"> pour la diffusion des publicit\u00e9s, qui peuvent ainsi \u00eatre cr\u00e9es \u00e0 partir des int\u00e9r\u00eats, des similitudes entre les caract\u00e9ristiques des clients, etc. ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><b>la cr\u00e9ation de catalogues de produits<\/b><span style=\"font-weight: 400;\"> pour aider \u00e0 la diffusion de votre e-commerce, en plus des boutiques Facebook et <\/span><span style=\"font-weight: 400;\">Instagram Shopping<\/span><span style=\"font-weight: 400;\">.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Tout cela peut \u00eatre partag\u00e9 avec votre \u00e9quipe pour faciliter l\u2019acc\u00e8s aux informations et le d\u00e9veloppement des actions. Si vous travaillez dans une agence, vous pouvez \u00e9galement acc\u00e9der aux actifs des entreprises par le biais d\u2019un partenariat.<\/span><\/p>\n<h3><br style=\"font-weight: 400;\" \/><strong>Les avantages de Facebook Business<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Lorsque vous utilisez Facebook Business au quotidien, un <\/span><b>ensemble d\u2019avantages et d\u2019opportunit\u00e9s<\/b><span style=\"font-weight: 400;\"> se pr\u00e9sente \u00e0 vous ainsi qu\u2019\u00e0 votre agence, tels que :<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">la facilit\u00e9 d\u2019acc\u00e9der et de g\u00e9rer la page et les comptes publicitaires sur un m\u00eame espace, sans qu\u2019il soit n\u00e9cessaire de se connecter plusieurs fois ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">l\u2019augmentation de la couverture de la marque et, par cons\u00e9quent, des ressources qui aident \u00e0 <\/span><span style=\"font-weight: 400;\">augmenter l\u2019engagement<\/span><span style=\"font-weight: 400;\"> avec le public, comme c\u2019est le cas du compte publicitaire ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">le partage des actifs avec les autres utilisateurs et agences, sans avoir besoin de partager des mots de passe ou des informations qui compromettent la confidentialit\u00e9 ou la s\u00e9curit\u00e9 de votre compte ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">le contr\u00f4le d\u2019actifs auxquels vous pouvez acc\u00e9der et que vous pouvez g\u00e9rer pour chaque collaborateur ou partenaire du compte ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">l\u2019acc\u00e8s pratique \u00e0 des activit\u00e9s vari\u00e9es li\u00e9es \u00e0 la page ou au profil d\u2019Instagram, ce qui rend la planification de publications, l\u2019enregistrement de messages et le suivi d\u2019insights plus productifs ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\"> \u00a0 \u00a0 \u00a0 <\/span><span style=\"font-weight: 400;\">la facilit\u00e9 d\u2019acc\u00e8s aux informations, tant sur un ordinateur qu\u2019au moyen d\u2019applications compatibles avec Android ou iOS.<\/span><\/li>\n<\/ul>\n<h2><br style=\"font-weight: 400;\" \/><strong>Comment cr\u00e9er un compte Facebook Business ?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Maintenant que vous en savez plus sur Facebook Business et ses avantages, il est temps de <\/span><b>d\u00e9couvrir comment cr\u00e9er votre compte et y ajouter des actifs<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le tutoriel \u00e0 suivre est tr\u00e8s simple :<\/span><\/p>\n<ol>\n<li><span style=\"font-weight: 400;\">Acc\u00e9dez au site Facebook Business<\/span> <span style=\"font-weight: 400;\">et cliquez sur \u00ab Cr\u00e9er un compte \u00bb ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Renseignez l\u2019adresse e-mail de l\u2019entreprise et, ensuite, le mot de passe ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Confirmez la cr\u00e9ation du compte depuis l\u2019adresse e-mail renseign\u00e9e.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Une fois le compte cr\u00e9\u00e9, vous pouvez y ajouter ou associer vos actifs, tels que la page, le compte publicitaires, Pixel, les applications, entre autres. D\u00e9couvrez ci-dessous des tutoriels \u00e0 suivre pour faire ces associations !<\/span><\/p>\n<h3><strong>Pages<\/strong><\/h3>\n<ol>\n<li><span style=\"font-weight: 400;\">Sur le compte Facebook Business Manager, acc\u00e9dez aux \u00ab Param\u00e8tres d\u2019entreprise \u00bb en haut \u00e0 gauche ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Cliquez sur \u00ab Comptes \u00bb et, ensuite, sur \u00ab Pages \u00bb ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Sur \u00ab Ajouter \u00bb, s\u00e9lectionnez l\u2019option qui vous convient le mieux : <\/span><b>Ajouter une page, Demander l\u2019acc\u00e8s \u00e0 une Page<\/b><span style=\"font-weight: 400;\"> ou <\/span><b>Cr\u00e9er une Page<\/b><span style=\"font-weight: 400;\">.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Si elle existe d\u00e9j\u00e0, vous devrez ajouter son URL pour que Facebook Business Manager la localise. Si elle est d\u00e9j\u00e0 associ\u00e9e \u00e0 un autre Gestionnaire, vous devrez d\u2019abord la d\u00e9sassocier.<\/span><\/li>\n<\/ol>\n<h3><br style=\"font-weight: 400;\" \/><strong>Comptes publicitaires<\/strong><\/h3>\n<ol>\n<li><span style=\"font-weight: 400;\">Sur \u00ab Comptes \u00bb, cliquez sur \u00ab Comptes Publicitaires \u00bb et acc\u00e9dez au bouton \u00ab Ajouter \u00bb ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Sur les options suivantes, vous aurez les m\u00eames options que sur l\u2019onglet des pages : <\/span><b>Ajouter un compte publicitaire, Demander l\u2019acc\u00e8s \u00e0 un compte publicitaire <\/b><span style=\"font-weight: 400;\">ou <\/span><b>Cr\u00e9er un compte publicitaire.<\/b><\/li>\n<li><span style=\"font-weight: 400;\">Si le compte existe d\u00e9j\u00e0, vous devrez ins\u00e9rer votre identifiant pour que le Gestionnaire puisse le localiser et l\u2019associer ;<\/span><\/li>\n<li><span style=\"font-size: 0.875rem;\">\u00a0<\/span><span style=\"font-weight: 400;\">Dans le cas o\u00f9 vous devez cr\u00e9er un nouveau compte, il vous faudra ins\u00e9rer les donn\u00e9es (dont le mode de paiement) et indiquer si vous cr\u00e9ez le compte pour votre propre entreprise ou pour un client.<\/span><\/li>\n<\/ol>\n<h3><strong>Cr\u00e9er un Pixel<\/strong><\/h3>\n<ol>\n<li><span style=\"font-weight: 400;\">Toujours dans les Param\u00e8tres d\u2019entreprise, acc\u00e9dez aux \u00ab <\/span><b>Sources de Donn\u00e9es<\/b><span style=\"font-weight: 400;\"> \u00bb et ensuite \u00e0 \u00ab <\/span><b>Pixels<\/b><span style=\"font-weight: 400;\"> \u00bb ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Ensuite, il suffit de cliquer sur \u00ab Ajouter \u00bb, d\u2019ins\u00e9rer le nom du Pixel et l\u2019URL du site.<\/span><\/li>\n<\/ol>\n<h3><br style=\"font-weight: 400;\" \/><strong>Ajouter des collaborateurs<\/strong><\/h3>\n<ol>\n<li><span style=\"font-weight: 400;\">Dans l\u2019onglet \u00ab <\/span><b>Utilisateurs<\/b><span style=\"font-weight: 400;\"> \u00bb, qui se trouve dans les Param\u00e8tres d\u2019entreprise, cliquez sur \u00ab <\/span><b>Personnes<\/b><span style=\"font-weight: 400;\"> \u00bb ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Renseignez l\u2019email de la personne que vous souhaitez ajouter ou s\u00e9lectionnez son profil Facebook ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Choisissez entre \u00ab Acc\u00e8s employ\u00e9 \u00bb ou \u00ab Acc\u00e8s administrateur \u00bb pour configurer les permissions ;<\/span><\/li>\n<li><span style=\"font-weight: 400;\">D\u00e9finissez le niveau d\u2019acc\u00e8s autoris\u00e9 pour l\u2019utilisateur et \u00e0 quels actifs il peut acc\u00e9der, tels que les pages, les comptes publicitaires, les catalogues etc.<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">En plus de ces actifs et de l\u2019ajout d\u2019utilisateurs \u00e0 Facebook Business Manager, vous pouvez <\/span><b>cr\u00e9er des catalogues de produits, int\u00e9grer d\u2019autres applications<\/b><span style=\"font-weight: 400;\"> ou <\/span><b>associer des comptes Instagram et WhatsApp Business<\/b><span style=\"font-weight: 400;\">. Tout comme les tutoriels que nous avons partag\u00e9s ci-dessus, ils sont tr\u00e8s faciles \u00e0 suivre.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il suffit d\u2019acc\u00e9der aux Param\u00e8tres d\u2019Entreprise et de chercher les ressources n\u00e9cessaires dans l\u2019onglet de gauche.<\/span><\/p>\n<h2><strong>Suivi des r\u00e9sultats sur Facebook<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Bien entendu, nous ne pouvions pas ne pas mentionner l\u2019acc\u00e8s aux r\u00e9sultats, que vous pouvez faire par le biais des <\/span><b>Insights de Facebook Business Suite<\/b><span style=\"font-weight: 400;\">. Gr\u00e2ce \u00e0 cet outil, vous pourrez suivre de pr\u00e8s les actions r\u00e9alis\u00e9es tant sur Facebook que sur Instagram.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vous pourrez garder un \u0153il sur toutes les activit\u00e9s r\u00e9alis\u00e9es sur les comptes, sur les objectifs de l\u2019entreprise, sur la couverture et l\u2019engagement, en plus de la croissance du public qui vous suit sur les deux r\u00e9seaux.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Comme \u00e9voqu\u00e9 pr\u00e9c\u00e9demment, il est tr\u00e8s pratique d\u2019y acc\u00e9der et de faire les analyses. Toutefois, si vous souhaitez ajouter de la facilit\u00e9 dans le processus de captation des indicateurs, nous vous conseillons d\u2019essayer les <\/span><b>rapports de Facebook <\/b><b>et d\u2019<\/b><b>Instagram<\/b><b> de <a href=\"https:\/\/app.reportei.com\/login?locale=fr&amp;\">Reportei<\/a><\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En quelques secondes, vous pourrez <\/span><b>acc\u00e9der aux donn\u00e9es de mani\u00e8re compl\u00e8te<\/b><span style=\"font-weight: 400;\">, que ce soient celles des profils ou du compte publicitaire, et ajouter des analyses sous la forme de textes, d\u2019images et de vid\u00e9o pour compl\u00e9ter les informations.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ainsi, vous rendrez non seulement le processus de cr\u00e9ation de rapports plus efficaces, mais vous simplifierez \u00e9galement la communication des r\u00e9sultats avec votre client ou d\u00e9cisionnaire !<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez ce que c\u2019est, ses avantages, et comment utiliser Facebook Business dans votre strat\u00e9gie de marketing digital<\/p>\n","protected":false},"author":18,"featured_media":26562,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[3725,3688,3689],"tags":[],"class_list":["post-26845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital-marketing","category-facebook-2","category-instagram-4"],"_links":{"self":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts\/26845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/comments?post=26845"}],"version-history":[{"count":0,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/posts\/26845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/media\/26562"}],"wp:attachment":[{"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/media?parent=26845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/categories?post=26845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reportei.com\/fr\/wp-json\/wp\/v2\/tags?post=26845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}